{"id":133028,"date":"2024-02-23T15:39:35","date_gmt":"2024-02-23T15:39:35","guid":{"rendered":"https:\/\/helpcenter.ila.cegid.com\/xrpenterprise\/\/"},"modified":"2024-02-23T15:39:35","modified_gmt":"2024-02-23T15:39:35","slug":"canales-de-cobro-y-pago","status":"publish","type":"xrpenterprise","link":"https:\/\/helpcenter.ila.cegid.com\/es\/xrpenterprise\/finanzas\/gestion-de-tesoreria\/cobros-y-pagos\/articulo\/canales-de-cobro-y-pago","title":{"rendered":"Canales de cobro y pago"},"content":{"rendered":"<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><p>Esta opci\u00f3n est\u00e1 disponible en <strong>Finanzas (Avanzado) | Gesti\u00f3n de tesorer\u00eda | Cobros y pagos.<\/strong><\/p>\n<\/div><\/section>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><h3>Conceptos b\u00e1sicos<\/h3>\n<p>Los canales de cobro o pago son los medios a trav\u00e9s de los que la entidad cobra o paga. Normalmente, esta funci\u00f3n la realizan los bancos a trav\u00e9s de las cuentas bancarias.<\/p>\n<p>Si dispone de varias cuentas en el mismo banco, es necesario definir tantos canales como cuentas existan en el banco.<\/p>\n<p>Desde un punto de vista m\u00e1s general, los c\u00f3digos de bancos tambi\u00e9n pueden identificar otros canales de cobro de facturas.<\/p>\n<h3>Funciones b\u00e1sicas<\/h3>\n<p>Desde este formulario puede definir o modificar los canales de cobro y pago.<\/p>\n<p>Despu\u00e9s de indicar un c\u00f3digo, un nombre y el resto de datos que considere oportunos, el canal queda definido.<\/p>\n<h3>Condiciones previas<\/h3>\n<ul>\n<li>Tener definidos los c\u00f3digos de entidad.<\/li>\n<li>Tener definida una cuenta de tesorer\u00eda y, por lo tanto, definir un plan contable general o auxiliar.<\/li>\n<li>Tener definidos los c\u00f3digos de pa\u00eds y provincias.<\/li>\n<\/ul>\n<h3>Elementos relacionados<\/h3>\n<p>Mediante el bot\u00f3n\u00a0<strong>Extracto<\/strong>\u00a0puede consultar el extracto de la cuenta contable asociada al canal en tratamiento.<\/p>\n<p>Tambi\u00e9n puede acceder al mantenimiento de los grupos y las series de numeraci\u00f3n que se utilizar\u00e1n en las \u00f3rdenes de pago, mediante el bot\u00f3n\u00a0<strong>Numeraciones<\/strong>.<\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2850,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","tags":[],"mercados":[432],"categoria-xrpenterprise":[6814],"class_list":["post-133028","xrpenterprise","type-xrpenterprise","status-publish","hentry","mercados-es","categoria-xrpenterprise-cobros-y-pagos"],"_links":{"self":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/xrpenterprise\/133028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/xrpenterprise"}],"about":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/types\/xrpenterprise"}],"author":[{"embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/users\/2850"}],"replies":[{"embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/comments?post=133028"}],"version-history":[{"count":0,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/xrpenterprise\/133028\/revisions"}],"wp:attachment":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/media?parent=133028"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/tags?post=133028"},{"taxonomy":"mercados","embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/mercados?post=133028"},{"taxonomy":"categoria-xrpenterprise","embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/categoria-xrpenterprise?post=133028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}