{"id":131162,"date":"2024-02-07T00:00:00","date_gmt":"2024-02-07T00:00:00","guid":{"rendered":"https:\/\/helpcenter.ila.cegid.com\/xrpenterprise\/\/"},"modified":"2024-03-25T09:01:39","modified_gmt":"2024-03-25T09:01:39","slug":"etiquetas-de-articulos-ean-13","status":"publish","type":"xrpenterprise","link":"https:\/\/helpcenter.ila.cegid.com\/es\/xrpenterprise\/almacenes-es\/articulos\/articulo\/etiquetas-de-articulos-ean-13","title":{"rendered":"Etiquetas de art\u00edculos EAN-13"},"content":{"rendered":"<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><p>Esta opci\u00f3n est\u00e1 disponible en <strong>Almacenes (Avanzado) | Art\u00edculos<\/strong>.<\/p>\n<\/div><\/section>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><h3>Conceptos b\u00e1sicos<\/h3>\n<p>El c\u00f3digo EAN es el sistema europeo de identificaci\u00f3n de art\u00edculos de gran consumo para facilitar su tratamiento en los puntos de venta. El c\u00f3digo est\u00e1 representado por barras paralelas de diferente grosor para permitir su lectura de forma autom\u00e1tica. En la parte inferior se incluyen generalmente las cifras representadas por el c\u00f3digo. Se conoce como c\u00f3digo de barras. Los c\u00f3digos de barras permiten evitar el marcado de precios y facilitar su variaci\u00f3n, llevar un inventario permanente con conocimiento exacto y r\u00e1pido de ventas y pedidos, y eliminar los errores de caja.<\/p>\n<p>El formato EAN-13 consta de 13 cifras: las dos primeras indican el pa\u00eds (en el caso de Espa\u00f1a, son las cifras 84); las cinco siguientes, el proveedor, seg\u00fan el n\u00famero que le asigne la Asociaci\u00f3n Nacional de Codificaci\u00f3n Comercial (AECOC en el territorio espa\u00f1ol); las cinco siguientes son las que el proveedor utiliza para cada uno de sus productos; y la \u00faltima es un d\u00edgito de control que asegura la fiabilidad de la lectura.<\/p>\n<h3>Funciones b\u00e1sicas<\/h3>\n<p>En este formulario puede imprimir las etiquetas de c\u00f3digos de barras (c\u00f3digo alternativo) de los art\u00edculos seg\u00fan el formato EAN-13. En este caso, emitiendo una o varias etiquetas por cada art\u00edculo pero de forma independiente a la cantidad entrada o a la existencia.<\/p>\n<p>Dispone de varios criterios de selecci\u00f3n para determinar la impresi\u00f3n de las etiquetas que desea imprimir: intervalo de art\u00edculos y\/o de proveedores, as\u00ed como la familia, la fecha de utilizaci\u00f3n o el n\u00famero de copias que desea obtener.<\/p>\n<h3>Condiciones previas<\/h3>\n<p>Para poder imprimir las etiquetas EAN-13 de un art\u00edculo, previamente debe indicar en el mantenimiento de art\u00edculos que \u00e9ste trabaja con c\u00f3digos EAN-13.<\/p>\n<h3>Elementos relacionados<\/h3>\n<p>En\u00a0<strong>Movimientos de almac\u00e9n<\/strong> hay otro proceso de etiquetado en el que puede imprimir etiquetas a partir de las entradas en el almac\u00e9n (una etiqueta por cada unidad entrada). Para m\u00e1s informaci\u00f3n vea <a href=\"https:\/\/helpcenter.ila.cegid.com\/es\/?helptopicid=1705667410&amp;prod=xrpenterprise\" target=\"_blank\" rel=\"noopener\">Etiquetas de movimientos EAN-13<\/a>.<\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2850,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","tags":[],"mercados":[432],"categoria-xrpenterprise":[6687],"class_list":["post-131162","xrpenterprise","type-xrpenterprise","status-publish","hentry","mercados-es","categoria-xrpenterprise-articulos"],"_links":{"self":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/xrpenterprise\/131162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/xrpenterprise"}],"about":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/types\/xrpenterprise"}],"author":[{"embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/users\/2850"}],"replies":[{"embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/comments?post=131162"}],"version-history":[{"count":0,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/xrpenterprise\/131162\/revisions"}],"wp:attachment":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/media?parent=131162"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/tags?post=131162"},{"taxonomy":"mercados","embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/mercados?post=131162"},{"taxonomy":"categoria-xrpenterprise","embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/categoria-xrpenterprise?post=131162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}