{"id":8905,"count":4,"description":"","link":"https:\/\/helpcenter.ila.cegid.com\/es\/xrpenterprise\/nomina\/empresas\/portal\/","name":"Portal","slug":"portal","taxonomy":"categoria-xrpenterprise","parent":8882,"meta":[],"_links":{"self":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/categoria-xrpenterprise\/8905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/categoria-xrpenterprise"}],"about":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/taxonomies\/categoria-xrpenterprise"}],"up":[{"embeddable":true,"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/categoria-xrpenterprise\/8882"}],"wp:post_type":[{"href":"https:\/\/helpcenter.ila.cegid.com\/es\/wp-json\/wp\/v2\/xrpenterprise?categoria-xrpenterprise=8905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}